{"id":2358,"date":"2018-07-02T18:18:36","date_gmt":"2018-07-02T18:18:36","guid":{"rendered":"http:\/\/acftransport.mtlwebdesign.com\/?page_id=2358&#038;lang=fr"},"modified":"2019-01-08T17:29:42","modified_gmt":"2019-01-08T17:29:42","slug":"services","status":"publish","type":"page","link":"https:\/\/www.acftransportaide.ca\/fr\/services\/","title":{"rendered":"Services"},"content":{"rendered":"<p>[vc_row][vc_column]<div class='content-over content-over--right'><div style='background-image: url(https:\/\/www.acftransportaide.ca\/wp-content\/uploads\/2018\/07\/trucks.png);' class='content-over__img'><\/div><div class='container'><div class='content-over__main'><h5 class='heading-content  style-1' ><span>Division du transport<\/span><\/h5>[vc_column_text]Chauffeurs qualifi\u00e9s pour\u00a0Transport\u00a0local et longue distance.<\/p>\n<p>Chez ACF Transportaide, \u00e0 Montr\u00e9al, nous sommes fiers de la qualit\u00e9 de nos relations avec nos clients, ainsi que de la qualit\u00e9 des candidats que nous fournissons. Nous r\u00e9pondons rapidement \u00e0 vos requ\u00eates et nous faisons tous les efforts n\u00e9cessaires pour bien r\u00e9pondre \u00e0 vos\u00a0besoins de main d\u2019\u0153uvre.<\/p>\n<p>[\/vc_column_text][vc_empty_space height=&#8221;10px&#8221;]<a target=\"_self\" href=\"\/transport-division\/?lang=fr\" class=\"btn btn-sm style-4\" id=\"custom-id-0\" style=\"\">EN SAVOIR PLUS<\/a><\/div><\/div><\/div>[vc_empty_space height=&#8221;60px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column]<div class='content-over content-over--right'><div style='background-image: url(https:\/\/www.acftransportaide.ca\/wp-content\/uploads\/2018\/07\/warehouse-work-1.jpg);' class='content-over__img'><\/div><div class='container'><div class='content-over__main'><h5 class='heading-content  style-1' ><span>Division du personnel<\/span><\/h5>[vc_column_text]Chez ACF Transportaide, \u00e0 Montr\u00e9al, nous sommes fiers de la qualit\u00e9 de nos relations avec nos clients, ainsi que de la qualit\u00e9 des candidats que nous fournissons. Nous r\u00e9pondons rapidement \u00e0 vos requ\u00eates et nous faisons tous les efforts n\u00e9cessaires pour bien r\u00e9pondre \u00e0 vos besoins de main d\u2019\u0153uvre.[\/vc_column_text][vc_empty_space height=&#8221;10px&#8221;]<a target=\"_self\" href=\"\/work-force-division\/?lang=fr\" class=\"btn btn-sm style-4\" id=\"custom-id-1\" style=\"\">EN SAVOIR PLUS<\/a><\/div><\/div><\/div>[vc_empty_space height=&#8221;60px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column]<div class='content-over content-over--right'><div style='background-image: url(https:\/\/www.acftransportaide.ca\/wp-content\/uploads\/2018\/06\/image-left-5.jpg);' class='content-over__img'><\/div><div class='container'><div class='content-over__main'><h5 class='heading-content  style-1' ><span>Division de bureau<\/span><\/h5>[vc_column_text]<strong>Nous nous occupons de la totalit\u00e9 du processus :<\/strong><br \/>\n\u2022 Profilage et affichage des emplois<br \/>\n\u2022 Description des t\u00e2ches<br \/>\n\u2022 \u00c9valuation de la formation et de l\u2019exp\u00e9rience<br \/>\n\u2022 \u00c9valuation des comp\u00e9tences<br \/>\n\u2022 Demandes d\u2019emplois par courriel<br \/>\n\u2022 Coordination des entrevues<br \/>\n\u2022 V\u00e9rification des r\u00e9f\u00e9rences<br \/>\n\u2022 S\u00e9lection finale<br \/>\n[\/vc_column_text][vc_empty_space height=&#8221;10px&#8221;]<a target=\"_self\" href=\"\/office-division\/?lang=fr\" class=\"btn btn-sm style-4\" id=\"custom-id-2\" style=\"\">SAVOIR PLUS<\/a><\/div><\/div><\/div>[vc_empty_space height=&#8221;60px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column]<div class='content-over content-over--right'><div style='background-image: url(https:\/\/www.acftransportaide.ca\/wp-content\/uploads\/2018\/07\/payrollcropped-1.jpg);' class='content-over__img'><\/div><div class='container'><div class='content-over__main'><h5 class='heading-content  style-1' ><span>Services de Paie<\/span><\/h5>[vc_column_text]Nos services de paie facilitent la gestion de votre flux de tr\u00e9sorerie, en vous offrant plus de flexibilit\u00e9, car nous prenons en charge tous les frais li\u00e9s \u00e0 l\u2019employ\u00e9 et au gouvernement pendant la p\u00e9riode d\u2019embauche. [\/vc_column_text][vc_empty_space height=&#8221;10px&#8221;]<a target=\"_self\" href=\"\/payroll-services\/?lang=fr\" class=\"btn btn-sm style-4\" id=\"custom-id-3\" style=\"\">SAVOIR PLUS<\/a><\/div><\/div><\/div>[vc_empty_space height=&#8221;60px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column]<div class='content-over content-over--right'><div style='background-image: url(https:\/\/www.acftransportaide.ca\/wp-content\/uploads\/2018\/06\/truck-driver.jpg);' class='content-over__img'><\/div><div class='container'><div class='content-over__main'><h5 class='heading-content  style-1' ><span>Demandeurs D&#8217;Emplois<\/span><\/h5>[vc_column_text]Nous offrons un service exceptionnel, de bons emplois de chauffeurs et nous sommes faciles \u00e0 joindre. Notre performance en termes de satisfaction des attentes de nos clients est si remarquable que plusieurs d\u2019entre eux ne demandent m\u00eame pas \u00e0 voir les candidats \u00e0 l\u2019avance. Nous avons r\u00e9ussi \u00e0 gagner leur confiance au fil des ans.[\/vc_column_text][vc_empty_space height=&#8221;10px&#8221;]<a target=\"_self\" href=\"\/job-seekers\/?lang=fr\" class=\"btn btn-sm style-4\" id=\"custom-id-4\" style=\"\">SAVOIR PLUS<\/a><\/div><\/div><\/div>[vc_empty_space height=&#8221;60px&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1530859268003{margin-top: 60px !important;}&#8221;][vc_column][vc_separator][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1514451897890{margin-top: 80px !important;margin-bottom: 110px !important;}&#8221;][vc_column el_class=&#8221;text-center&#8221;][vc_custom_heading text=&#8221;Satisfaction garantie&#8221; font_container=&#8221;tag:h3|font_size:32px|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1530859302589{padding-bottom: 10px !important;}&#8221;][vc_custom_heading text=&#8221;Nous sommes tellement confiants que vous serez satisfaits de notre s\u00e9lection que nous offrons une garantie pour chaque placement effectu\u00e9 par ACF.&#8221; font_container=&#8221;tag:p|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_custom_heading text=&#8221;N&#8217;h\u00e9sitez pas \u00e0 nous contacter quand vous le souhaitez&#8221; font_container=&#8221;tag:h3|font_size:32px|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1530859309144{padding-bottom: 10px !important;}&#8221;][vc_empty_space height=&#8221;20px&#8221;]<a target=\"_self\" href=\"\/contact-us\/\" class=\"btn btn-md style-1\" id=\"custom-id-5\" style=\"\"> Appelez-nous<\/a>[\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_empty_space height=&#8221;60px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;60px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;60px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;60px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;60px&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1530859268003{margin-top: 60px !important;}&#8221;][vc_column][vc_separator][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1514451897890{margin-top: 80px !important;margin-bottom: 110px !important;}&#8221;][vc_column el_class=&#8221;text-center&#8221;][vc_custom_heading text=&#8221;Satisfaction garantie&#8221; font_container=&#8221;tag:h3|font_size:32px|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1530859302589{padding-bottom: 10px !important;}&#8221;][vc_custom_heading text=&#8221;Nous sommes tellement confiants que vous serez satisfaits de notre s\u00e9lection que nous offrons une garantie pour chaque&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"class_list":["post-2358","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Services | ACF TRANSPORTAIDE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.acftransportaide.ca\/fr\/services\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Services\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_empty_space height=&#8221;60px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;60px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;60px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;60px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;60px&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1530859268003{margin-top: 60px !important;}&#8221;][vc_column][vc_separator][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1514451897890{margin-top: 80px !important;margin-bottom: 110px !important;}&#8221;][vc_column el_class=&#8221;text-center&#8221;][vc_custom_heading text=&#8221;Satisfaction garantie&#8221; font_container=&#8221;tag:h3|font_size:32px|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1530859302589{padding-bottom: 10px !important;}&#8221;][vc_custom_heading text=&#8221;Nous sommes tellement confiants que vous serez satisfaits de notre s\u00e9lection que nous offrons une garantie pour chaque...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.acftransportaide.ca\/fr\/services\/\" \/>\n<meta property=\"og:site_name\" content=\"Employment Agency Montreal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acftransportaide\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-08T17:29:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Services | ACF TRANSPORTAIDE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.acftransportaide.ca\/fr\/services\/","og_locale":"fr_FR","og_type":"article","og_title":"Services","og_description":"[vc_row][vc_column][vc_empty_space height=&#8221;60px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;60px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;60px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;60px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;60px&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1530859268003{margin-top: 60px !important;}&#8221;][vc_column][vc_separator][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1514451897890{margin-top: 80px !important;margin-bottom: 110px !important;}&#8221;][vc_column el_class=&#8221;text-center&#8221;][vc_custom_heading text=&#8221;Satisfaction garantie&#8221; font_container=&#8221;tag:h3|font_size:32px|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1530859302589{padding-bottom: 10px !important;}&#8221;][vc_custom_heading text=&#8221;Nous sommes tellement confiants que vous serez satisfaits de notre s\u00e9lection que nous offrons une garantie pour chaque...","og_url":"https:\/\/www.acftransportaide.ca\/fr\/services\/","og_site_name":"Employment Agency Montreal","article_publisher":"https:\/\/www.facebook.com\/acftransportaide","article_modified_time":"2019-01-08T17:29:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.acftransportaide.ca\/fr\/services\/","url":"https:\/\/www.acftransportaide.ca\/fr\/services\/","name":"Services | ACF TRANSPORTAIDE","isPartOf":{"@id":"https:\/\/www.acftransportaide.ca\/fr\/#website"},"datePublished":"2018-07-02T18:18:36+00:00","dateModified":"2019-01-08T17:29:42+00:00","breadcrumb":{"@id":"https:\/\/www.acftransportaide.ca\/fr\/services\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.acftransportaide.ca\/fr\/services\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.acftransportaide.ca\/fr\/services\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.acftransportaide.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Services"}]},{"@type":"WebSite","@id":"https:\/\/www.acftransportaide.ca\/fr\/#website","url":"https:\/\/www.acftransportaide.ca\/fr\/","name":"ACF TRANSPORTAIDE","description":"Montreal Transport agency","publisher":{"@id":"https:\/\/www.acftransportaide.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.acftransportaide.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.acftransportaide.ca\/fr\/#organization","name":"ACF Transportaide","url":"https:\/\/www.acftransportaide.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.acftransportaide.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.acftransportaide.ca\/wp-content\/uploads\/2018\/12\/ACF-Logo.png","contentUrl":"https:\/\/www.acftransportaide.ca\/wp-content\/uploads\/2018\/12\/ACF-Logo.png","width":225,"height":115,"caption":"ACF Transportaide"},"image":{"@id":"https:\/\/www.acftransportaide.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acftransportaide"]}]}},"_links":{"self":[{"href":"https:\/\/www.acftransportaide.ca\/fr\/wp-json\/wp\/v2\/pages\/2358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.acftransportaide.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.acftransportaide.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.acftransportaide.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.acftransportaide.ca\/fr\/wp-json\/wp\/v2\/comments?post=2358"}],"version-history":[{"count":13,"href":"https:\/\/www.acftransportaide.ca\/fr\/wp-json\/wp\/v2\/pages\/2358\/revisions"}],"predecessor-version":[{"id":2938,"href":"https:\/\/www.acftransportaide.ca\/fr\/wp-json\/wp\/v2\/pages\/2358\/revisions\/2938"}],"wp:attachment":[{"href":"https:\/\/www.acftransportaide.ca\/fr\/wp-json\/wp\/v2\/media?parent=2358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}